{"id":23618,"date":"2020-11-29T08:22:10","date_gmt":"2020-11-29T11:22:10","guid":{"rendered":"https:\/\/universonerd.net\/portal\/?p=23618"},"modified":"2020-11-29T08:22:13","modified_gmt":"2020-11-29T11:22:13","slug":"conheca-o-aviao-eletrico-que-fez-decolagem-e-pouso-na-direcao-vertical","status":"publish","type":"post","link":"https:\/\/universonerd.net\/portal\/conheca-o-aviao-eletrico-que-fez-decolagem-e-pouso-na-direcao-vertical\/","title":{"rendered":"Conhe\u00e7a O Avi\u00e3o El\u00e9trico Que Fez Decolagem e Pouso Na Dire\u00e7\u00e3o Vertical"},"content":{"rendered":"<p><span style=\"color: #000000;\">O <strong>avi\u00e3o el\u00e9trico<\/strong> \u00e9 visto como uma poss\u00edvel solu\u00e7\u00e3o na redu\u00e7\u00e3o de danos considerando a crescente contribui\u00e7\u00e3o da avia\u00e7\u00e3o para emiss\u00f5es de gases, al\u00e9m de quest\u00f5es econ\u00f4micas. Nesse contexto, v\u00e1rios fabricantes est\u00e3o desenvolvendo modernos prot\u00f3tipos, focando tamb\u00e9m na redu\u00e7\u00e3o no consumo de combust\u00edvel, hoje o principal custo das companhias a\u00e9reas em todo o mundo.<\/span><\/p>\n<p><span style=\"color: #000000;\">A empresa alem\u00e3 <strong>Lilium<\/strong> realizou com sucesso o <strong>primeiro teste de voo do seu avi\u00e3o el\u00e9trico incluindo as capacidades de decolagem e pouso na dire\u00e7\u00e3o vertical. <\/strong>Uma das caracter\u00edsticas mais marcantes em rela\u00e7\u00e3o aos avi\u00f5es tradicionais com a mesma capacidade, que precisam girar seus rotores, \u00e9 a simplicidade deste projeto. Com 36 motores el\u00e9tricos fornecendo empuxo instant\u00e2neo em quase todas as dire\u00e7\u00f5es, as superf\u00edcies de controle, como lemes ou cauda, n\u00e3o s\u00e3o necess\u00e1rias.<\/span><\/p>\n<p><span style=\"color: #000000;\">Al\u00e9m disso, a tamb\u00e9m elimina\u00e7\u00e3o dos circuitos de lubrifica\u00e7\u00e3o e das caixas de c\u00e2mbio ajuda a diminuir o peso para comportar as baterias e contribui para que o avi\u00e3o el\u00e9trico tenha aproximadamente o mesmo n\u00famero de pe\u00e7as individuais que um carro padr\u00e3o, o que \u00e9 1.000 vezes menos pe\u00e7as do que um jato tradicional.<\/span><\/p>\n<blockquote>\n<p><span style=\"color: #000000;\"><em><strong>Tornar a aeronave mais simples e r\u00e1pida de projetar significa menos manuten\u00e7\u00e3o e custo de opera\u00e7\u00e3o!<\/strong><\/em><\/span><\/p>\n<\/blockquote>\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Lilium Full Flight\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/ljHMdkzzF_Y?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/universonerd.net\/portal\/wp-content\/uploads\/2020\/11\/aviao-eletrico-vertical.jpg\" alt=\"\" class=\"wp-image-23622\" srcset=\"https:\/\/universonerd.net\/portal\/wp-content\/uploads\/2020\/11\/aviao-eletrico-vertical.jpg 768w, https:\/\/universonerd.net\/portal\/wp-content\/uploads\/2020\/11\/aviao-eletrico-vertical-300x169.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n<p><span style=\"color: #000000;\">A empresa alem\u00e3 est\u00e1 otimista de que seu novo projeto de <strong>avi\u00e3o el\u00e9trico<\/strong> possa entrar no mercado de avia\u00e7\u00e3o regional em poucos anos, afirmando que o objetivo desta aeronave \u00e9&#8230;<\/span><\/p>\n<blockquote>\n<p><em><span style=\"color: #000000;\"><strong>&#8230; equilibrar os requisitos concorrentes de alcance, velocidade e carga \u00fatil, ao mesmo tempo que oferece baixo ru\u00eddo e os mesmos padr\u00f5es de seguran\u00e7a das atuais aeronaves comerciais<\/strong>.<\/span><\/em><\/p>\n<\/blockquote>\n<p><span style=\"color: #000000;\">As quatro asas contribuem para a efici\u00eancia geral, fornecendo sustenta\u00e7\u00e3o para suportar o peso da aeronave durante o voo horizontal, enquanto o projeto em duto dos motores el\u00e9tricos fornece uma vantagem de efici\u00eancia em rela\u00e7\u00e3o aos rotores abertos, bloqueando a forma\u00e7\u00e3o de v\u00f3rtices, ou fluxos em turbilh\u00e3o.<\/span><\/p>\n<p><span style=\"color: #000000;\">Por fim, trabalhos de modelagem ac\u00fastica permitiram construir motores que tornam a aeronave inaud\u00edvel do solo quando ela voa acima de 400 metros de altitude, fazendo o mesmo barulho de um caminh\u00e3o passando durante a decolagem. Interessante, n\u00e3o? Come\u00e7a a corrida pelo futuro da avia\u00e7\u00e3o!<\/span><\/p>\n\n\n<p><strong>________________________________________________________________________<\/strong>______<\/p>\n\n\n<p><span style=\"color: #000000;\"><strong data-rich-text-format-boundary=\"true\">Fonte:<\/strong> Inova\u00e7\u00e3o Tecnol\u00f3gica e Canal do YouTube Lilium.<\/span><\/p>\n\n\n<p><em><strong>Se voc\u00ea gostou, n\u00e3o deixe de participar atrav\u00e9s de sugest\u00f5es, cr\u00edticas e\/ou d\u00favidas. Aproveitem para assinar o Blog, curtir a <\/strong><\/em><a href=\"https:\/\/facebook.com\/universonerd.net\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>P\u00e1gina no Facebook<\/strong><\/a><em><strong>, interagir no <\/strong><\/em><a href=\"https:\/\/www.facebook.com\/groups\/1285723958213451\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Grupo do Facebook<\/strong><\/a><em><strong>, al\u00e9m de acompanhar publica\u00e7\u00f5es e ficar por dentro do Projeto Universo NERD, de sorteios, concursos e demais promo\u00e7\u00f5es.<\/strong><\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O avi\u00e3o el\u00e9trico \u00e9 visto como uma poss\u00edvel solu\u00e7\u00e3o na redu\u00e7\u00e3o de danos considerando a crescente contribui\u00e7\u00e3o da avia\u00e7\u00e3o para emiss\u00f5es de gases, al\u00e9m de quest\u00f5es econ\u00f4micas. Nesse contexto, v\u00e1rios fabricantes est\u00e3o desenvolvendo modernos prot\u00f3tipos, focando tamb\u00e9m na redu\u00e7\u00e3o no consumo de combust\u00edvel, hoje o principal custo das companhias a\u00e9reas em todo o mundo. A empresa alem\u00e3 Lilium realizou com sucesso o primeiro teste de voo do seu avi\u00e3o el\u00e9trico incluindo as capacidades de decolagem e pouso na dire\u00e7\u00e3o vertical. Uma das caracter\u00edsticas mais marcantes em rela\u00e7\u00e3o aos avi\u00f5es tradicionais com a mesma capacidade, que precisam girar seus rotores, \u00e9 a simplicidade deste projeto. Com 36 motores el\u00e9tricos fornecendo empuxo instant\u00e2neo em quase todas as dire\u00e7\u00f5es, as superf\u00edcies de controle, como lemes ou cauda, n\u00e3o s\u00e3o necess\u00e1rias. Al\u00e9m disso, a tamb\u00e9m elimina\u00e7\u00e3o dos circuitos de lubrifica\u00e7\u00e3o e das caixas de c\u00e2mbio ajuda a diminuir o peso para comportar as baterias e contribui para que o avi\u00e3o el\u00e9trico tenha aproximadamente o mesmo n\u00famero de pe\u00e7as individuais que um carro padr\u00e3o, o que \u00e9 1.000 vezes menos pe\u00e7as do que um jato tradicional. Tornar a aeronave mais simples e r\u00e1pida de projetar significa menos manuten\u00e7\u00e3o e custo de opera\u00e7\u00e3o! A empresa alem\u00e3 est\u00e1 otimista de que seu novo projeto de avi\u00e3o el\u00e9trico possa entrar no mercado de avia\u00e7\u00e3o regional em poucos anos, afirmando que o objetivo desta aeronave \u00e9&#8230; &#8230; equilibrar os requisitos concorrentes de alcance, velocidade e carga \u00fatil, ao mesmo tempo que oferece baixo ru\u00eddo e os mesmos padr\u00f5es de seguran\u00e7a das atuais aeronaves comerciais. As quatro asas contribuem para a efici\u00eancia geral, fornecendo sustenta\u00e7\u00e3o para suportar o peso da aeronave durante o voo horizontal, enquanto o projeto em duto dos motores el\u00e9tricos fornece uma vantagem de efici\u00eancia em rela\u00e7\u00e3o aos rotores abertos, bloqueando a forma\u00e7\u00e3o de v\u00f3rtices, ou fluxos em turbilh\u00e3o. Por fim, trabalhos de modelagem ac\u00fastica permitiram construir motores que tornam a aeronave inaud\u00edvel do solo quando ela voa acima de 400 metros de altitude, fazendo o mesmo barulho de um caminh\u00e3o passando durante a decolagem. Interessante, n\u00e3o? Come\u00e7a a corrida pelo futuro da avia\u00e7\u00e3o! ______________________________________________________________________________ Fonte: Inova\u00e7\u00e3o Tecnol\u00f3gica e Canal do YouTube Lilium. Se voc\u00ea gostou, n\u00e3o deixe de participar atrav\u00e9s de sugest\u00f5es, cr\u00edticas e\/ou d\u00favidas. Aproveitem para assinar o Blog, curtir a P\u00e1gina no Facebook, interagir no Grupo do Facebook, al\u00e9m de acompanhar publica\u00e7\u00f5es e ficar por dentro do Projeto Universo NERD, de sorteios, concursos e demais promo\u00e7\u00f5es.<\/p>\n","protected":false},"author":3,"featured_media":23624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[25,1,38],"tags":[3433,3434,3436,3435,40],"class_list":["post-23618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","category-todascategorias","category-videos","tag-aviao-eletrico","tag-decolagem-vertical","tag-lilium","tag-pouso-vertical","tag-tecnologia"],"_links":{"self":[{"href":"https:\/\/universonerd.net\/portal\/wp-json\/wp\/v2\/posts\/23618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/universonerd.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/universonerd.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/universonerd.net\/portal\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/universonerd.net\/portal\/wp-json\/wp\/v2\/comments?post=23618"}],"version-history":[{"count":0,"href":"https:\/\/universonerd.net\/portal\/wp-json\/wp\/v2\/posts\/23618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/universonerd.net\/portal\/wp-json\/wp\/v2\/media\/23624"}],"wp:attachment":[{"href":"https:\/\/universonerd.net\/portal\/wp-json\/wp\/v2\/media?parent=23618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/universonerd.net\/portal\/wp-json\/wp\/v2\/categories?post=23618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/universonerd.net\/portal\/wp-json\/wp\/v2\/tags?post=23618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}